{"id":15151,"date":"2026-07-15T16:34:27","date_gmt":"2026-07-15T14:34:27","guid":{"rendered":"https:\/\/monbitcoin.fr\/index.php\/2026\/07\/15\/le-ceo-de-coinbase-ladmet-nous-nous-sommes-plantes-avec-les-creator-coins\/"},"modified":"2026-07-15T16:34:27","modified_gmt":"2026-07-15T14:34:27","slug":"le-ceo-de-coinbase-ladmet-nous-nous-sommes-plantes-avec-les-creator-coins","status":"publish","type":"post","link":"https:\/\/monbitcoin.fr\/index.php\/2026\/07\/15\/le-ceo-de-coinbase-ladmet-nous-nous-sommes-plantes-avec-les-creator-coins\/","title":{"rendered":"Le CEO de Coinbase l&rsquo;admet : \u00ab nous nous sommes plant\u00e9s \u00bb avec les creator coins"},"content":{"rendered":"<div>\n<p>Le layer 2 Base a-t-il fait une promotion trop importante des creator coins lors de l\u2019engouement autour de la SocialFi ? De toute \u00e9vidence, selon le CEO de Coinbase, Brian Armstrong, qui admet s\u2019\u00eatre \u00ab plant\u00e9 \u00bb sur le sujet. Mais encore&#8230;<\/p>\n<p>L\u2019article <a href=\"https:\/\/cryptoast.fr\/ceo-coinbase-admet-sommes-plantes-avec-creator-coins\/\">Le CEO de Coinbase l&rsquo;admet : \u00ab nous nous sommes plant\u00e9s \u00bb avec les creator coins<\/a> est apparu en premier sur <a href=\"https:\/\/cryptoast.fr\/\">Cryptoast<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le layer 2 Base a-t-il fait une promotion trop importante des creator coins lors de l\u2019engouement autour de la SocialFi&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-15151","post","type-post","status-publish","format-standard","hentry","category-dernier-articles","wpcat-3-id"],"_links":{"self":[{"href":"https:\/\/monbitcoin.fr\/index.php\/wp-json\/wp\/v2\/posts\/15151"}],"collection":[{"href":"https:\/\/monbitcoin.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monbitcoin.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monbitcoin.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monbitcoin.fr\/index.php\/wp-json\/wp\/v2\/comments?post=15151"}],"version-history":[{"count":0,"href":"https:\/\/monbitcoin.fr\/index.php\/wp-json\/wp\/v2\/posts\/15151\/revisions"}],"wp:attachment":[{"href":"https:\/\/monbitcoin.fr\/index.php\/wp-json\/wp\/v2\/media?parent=15151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monbitcoin.fr\/index.php\/wp-json\/wp\/v2\/categories?post=15151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monbitcoin.fr\/index.php\/wp-json\/wp\/v2\/tags?post=15151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}